{"id":762,"date":"2012-07-18T12:27:24","date_gmt":"2012-07-18T17:27:24","guid":{"rendered":"http:\/\/www.cortig.net\/localisations\/?p=762"},"modified":"2012-07-18T12:27:25","modified_gmt":"2012-07-18T17:27:25","slug":"deces-devan-gross","status":"publish","type":"post","link":"https:\/\/www.cortig.net\/localisations\/2012\/07\/18\/deces-devan-gross\/","title":{"rendered":"D\u00e9c\u00e8s d\u2019Evan Gross"},"content":{"rendered":"<p>Evan Gross, auteur de <a href=\"http:\/\/www.rainmakerinc.com\">Spell Catcher X<\/a> est d\u00e9c\u00e9d\u00e9  il y a quelques jours. J\u2019ai appris la nouvelle par <a href=\"http:\/\/www.rainmakerinc.com\/blog\/2012\/07\/12\/evan-michael-gross-has-passed-away\/\">le blog de son site<\/a>.<br \/>\nL\u2019\u00e9v\u00e9nement a \u00e9t\u00e9 aussi soudain qu\u2019inattendu pour moi. J\u2019ai travaill\u00e9 sur les localisations de SCX avec Ronald depuis plusieurs ann\u00e9es et Evan \u00e9tait un d\u00e9veloppeur \u00e0 la fois extr\u00eamement talentueux et d\u00e9vou\u00e9.<br \/>\nJ\u2019ai \u00e9t\u00e9 d\u2019ailleurs surpris que la nouvelle ne soit pas plus reprise sur les divers sites de nouvelles Mac.<\/p>","protected":false},"excerpt":{"rendered":"<p>Evan Gross, auteur de Spell Catcher X est d\u00e9c\u00e9d\u00e9 il y a quelques jours. J\u2019ai appris la nouvelle par le blog de son site. L\u2019\u00e9v\u00e9nement a \u00e9t\u00e9 aussi soudain qu\u2019inattendu pour moi. J\u2019ai travaill\u00e9 sur les localisations de SCX avec Ronald depuis plusieurs ann\u00e9es et Evan \u00e9tait un d\u00e9veloppeur \u00e0 la fois extr\u00eamement talentueux et d\u00e9vou\u00e9. J\u2019ai \u00e9t\u00e9 d\u2019ailleurs surpris que la nouvelle ne soit pas plus reprise sur les divers sites de nouvelles Mac.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,2],"tags":[],"class_list":["post-762","post","type-post","status-publish","format-standard","hentry","category-localisations-de-corentin-cras-meneur","category-localisations-de-ronald-leroux"],"_links":{"self":[{"href":"https:\/\/www.cortig.net\/localisations\/wp-json\/wp\/v2\/posts\/762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortig.net\/localisations\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cortig.net\/localisations\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cortig.net\/localisations\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cortig.net\/localisations\/wp-json\/wp\/v2\/comments?post=762"}],"version-history":[{"count":2,"href":"https:\/\/www.cortig.net\/localisations\/wp-json\/wp\/v2\/posts\/762\/revisions"}],"predecessor-version":[{"id":764,"href":"https:\/\/www.cortig.net\/localisations\/wp-json\/wp\/v2\/posts\/762\/revisions\/764"}],"wp:attachment":[{"href":"https:\/\/www.cortig.net\/localisations\/wp-json\/wp\/v2\/media?parent=762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cortig.net\/localisations\/wp-json\/wp\/v2\/categories?post=762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cortig.net\/localisations\/wp-json\/wp\/v2\/tags?post=762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}